{"id":48353,"date":"2021-06-21T12:00:00","date_gmt":"2021-06-21T17:00:00","guid":{"rendered":"https:\/\/atomic-temporary-84115225.wpcomstaging.com\/?p=48353"},"modified":"2021-06-21T12:00:00","modified_gmt":"2021-06-21T17:00:00","slug":"entrevista-con-winder","status":"publish","type":"post","link":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/","title":{"rendered":"Entrevista con Winder"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Winder<\/strong> es un cantautor e int\u00e9rprete de nacionalidad mexicana que recientemente lanz\u00f3 su nuevo sencillo \u201c<strong>Vali\u00f3 la pena<\/strong>\u201d, un tema que forma parte de su sexta placa discogr\u00e1fica que saldr\u00e1 en las pr\u00f3ximas semanas.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link\">Por C\u00e9sar Palomares<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s este tema est\u00e1 acompa\u00f1ado de un material visual, que fue grabado en paradis\u00edacas vistas de Quintana Roo, M\u00e9xico.<br><br>\u00bfQuieres saber qu\u00e9 nos cont\u00f3?, checa toda la entrevista.<\/p>\n\n\n\n<div style=\"height:10px;\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 significa compartir este nuevo sencillo al p\u00fablico?<br><\/strong><br>\u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d es una suma de esfuerzos, desvelos, malas pasadas y logros. Es como un resumen de tantos a\u00f1os que hemos andado en el camino y de la escuela que me ha tocado vivir, estoy muy agradecido porque tener esta escuela me ha dado la oportunidad de conocer bien el camino y pisar fuerte cada escal\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante saber esperar y este sencillo es el ejemplo de mi carrera, \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d naci\u00f3 hace cuatro a\u00f1os, pero pens\u00e9 que no era el momento ideal para lanzarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue un a\u00f1o muy dif\u00edcil, pero agradezco por este tiempo que nos dio la vida, me pude organizar mejor y darme cuenta de muchas cosas, que estaba haciendo bien y que no. \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d fue una de estas partes que se organiz\u00f3 y se decidi\u00f3 lanzar cuando las cosas fluyeran otra vez, cuando llegara la vacuna y gracias a Dios se dio muy bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Decidimos que mayo era un mes espectacular para poder estrenar \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d, es una canci\u00f3n que yo quiero mucho.<br><br><strong>\u00bfQu\u00e9 hay detr\u00e1s de esta nueva producci\u00f3n?<\/strong><br><br>Este nuevo tema habla de enamoramiento, romance y amor, pero tambi\u00e9n le encuentro un significado m\u00e1s all\u00e1 del amor, yo le pongo a mis metas \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d, por supuesto que vali\u00f3 la pena todos los a\u00f1os de trabajo, este es punto donde yo digo \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d, ya trabajamos, ya aprendimos, ya la regamos.<br><br>Ya cumpl\u00ed el prop\u00f3sito, yo invito a la gente a que tomen este ejemplo o esta influencia para decir: <em>\u201ceste chavo trabajo por m\u00e1s de quince a\u00f1os para llegar a este momento\u201d<\/em> y claro que para m\u00ed esto no ha terminado, \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d es a largo plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empezamos desde cero pr\u00e1cticamente, con un nuevo disco, con una nueva gira, m\u00e1s producciones, todos debemos tener nuestro propio \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d en el cual estemos trabajando para un d\u00eda poder decir:<em> \u201ctrabaje tanto, o tal vez no lo logr\u00e9, pero la vali\u00f3 la pena porque aprend\u00ed y me levante, vamos a continuar\u201d<\/em>.<\/p>\n\n\n\n<div class=\"wp-block-image coblocks-animate\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/81a8c-foto-para-contenido-entrevista-con-winder-1.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/81a8c-foto-para-contenido-entrevista-con-winder-1.jpg?w=1165&#038;ssl=1\" alt=\"\" class=\"wp-image-48360\" \/><\/a><\/figure><\/div>\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo fue colaborar con Jair Alcal\u00e1?<\/strong><br><br>Yo quer\u00eda fusionar sonidos que me gustan, siempre he sido muy ac\u00fastico, quer\u00eda incorporar el acorde\u00f3n que es un instrumento caracter\u00edstico del norte, me pregunt\u00e9 c\u00f3mo lo pod\u00edamos fusionar y tom\u00e9 la decisi\u00f3n de marcarle a <strong>Jair <\/strong>y pedirle esta colaboraci\u00f3n y \u00e9l sin pensarlo me dijo que s\u00ed, se port\u00f3 incre\u00edble y creo que le dej\u00f3 un toque muy especial a \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfPor qu\u00e9 decidiste grabar este tema en Tulum, Quintana Roo?<\/strong><strong><br><\/strong><br>Hace algunos a\u00f1os conoc\u00ed a un fot\u00f3grafo que trabaja mucho debajo del agua, como en los cenotes de Tulum y Playa del Carmen. Cuando yo conozco su trabajo supe que en alg\u00fan momento ten\u00eda que colaborar con \u00e9l, fue como una meta que me puse. Hasta hace aproximadamente un a\u00f1o logramos coincidir para realizar esta sesi\u00f3n, hubo una gran qu\u00edmica y pens\u00e9 en que no pod\u00eda quedarse solamente en fotograf\u00eda, pens\u00e9 en realizar un video, pero tambi\u00e9n s\u00e9 que para la fotograf\u00eda no se necesita tanta producci\u00f3n y para un video s\u00ed.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese momento comenc\u00e9 a trabajar la idea y ponerla sobre la mesa, llevarlo a cabo fue una tarea muy dif\u00edcil, pero al final el resultado fue incre\u00edble, fue muy bonito el proceso, pero tambi\u00e9n hubo mucho estr\u00e9s, salir de tu ciudad a un lugar donde eres nuevo pr\u00e1cticamente, fue dif\u00edcil, pero creo que se logr\u00f3 el objetivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1ndo podremos escuchar tu disco completo?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pr\u00f3ximo 25 de junio saldr\u00e1 en las plataformas digitales, se llama igual que la canci\u00f3n \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d, vienen incluidos once temas, cuatro de ellos ya los hemos escuchado anteriormente, pero ahora decidimos mostrarles el disco completo, escucharan \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d con m\u00e1s ritmo y sabor, tambi\u00e9n escucharemos canciones de desamor y olvido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al final la m\u00fasica nos ayuda a sanar, recordar y olvidar, yo creo que la m\u00fasica es parte del proceso de sanaci\u00f3n de muchas personas, les voy a compartir varios temas que les va ayudar a superar procesos dif\u00edciles.<\/p>\n\n\n\n<div class=\"wp-block-image coblocks-animate\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/e64d3-foto-para-contenido-entrevista-con-winderx.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/e64d3-foto-para-contenido-entrevista-con-winderx.jpg?w=1165&#038;ssl=1\" alt=\"\" class=\"wp-image-48362\" \/><\/a><\/figure><\/div>\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfTienes planeado realizar una gira?<\/strong><br><br>S\u00ed, de hecho, comenzamos el<strong><em> 1 de julio en Monterrey, 3 de julio en Saltillo, 8 de julio en Le\u00f3n, 9 de julio en Aguascalientes<\/em><\/strong> y despu\u00e9s brincamos a <strong><em>San Luis Potos\u00ed, Zacatecas <\/em><\/strong>y<strong><em> Guatemala<\/em><\/strong>. <strong><em>Tijuana, Mexicali<\/em><\/strong> y <strong><em>Guadalajara <\/em><\/strong>ser\u00e1n en el mes de agosto, estoy muy contento porque nunca hab\u00eda lanzado una gira tan grande y esta vez se est\u00e1 logrando poco a poco el objetivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfTe gustar\u00eda realizar alguna colaboraci\u00f3n durante este proceso?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed ya tenemos planes, con \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d me gustar\u00eda incursionar en el g\u00e9nero urbano, yo no, pero s\u00ed colaborar con alguien que est\u00e9 involucrado en el g\u00e9nero, estamos buscando esa opci\u00f3n. Me gustar\u00eda hacer una colaboraci\u00f3n con <strong>Los Claxons<\/strong>, tambi\u00e9n me gustar\u00eda realizar algo con <strong>Carlos Vives<\/strong>, son cosas que estamos tratando de lograr.<\/p>\n\n\n\n<div class=\"wp-block-image coblocks-animate\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/2c098-foto-para-contenido-entrevista-con-winderr.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/2c098-foto-para-contenido-entrevista-con-winderr.jpg?w=1165&#038;ssl=1\" alt=\"\" class=\"wp-image-48364\" \/><\/a><\/figure><\/div>\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Han pasado dos a\u00f1os aproximadamente desde la publicaci\u00f3n de tu \u00faltimo disco \u201cLos covers de Winder\u201d, \u00bfQu\u00e9 es lo que m\u00e1s te emociona en esta nueva etapa?<br><\/strong><br>El poder ver a lo largo de seis discos, que est\u00e1n ah\u00ed y se han trabajado. Justamente hoy vi un recuerdo en <strong>Facebook <\/strong>de hace seis a\u00f1os, publiqu\u00e9 algo as\u00ed como de \u201c<em>vivir ciclos<\/em>\u201d, hace seis a\u00f1os estaba cerrando un ciclo con una agrupaci\u00f3n, yo siempre he dicho que a un proyecto hay que entregarse y dejar el coraz\u00f3n, en esa \u00e9poca recuerdo que estaba en esa posici\u00f3n y tal vez los compa\u00f1eros no, decid\u00ed alejarme y convertirme en solista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese tiempo realic\u00e9 una publicaci\u00f3n donde me declaraba solista y promet\u00ed un disco y de repente llegar al sexto disco y ver la evoluci\u00f3n que ha habido es muy emocionante. Ver que \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d est\u00e1 teniendo aceptaci\u00f3n, eso me tiene muy feliz y con muchas ganas de trabajar, porque con este \u00faltimo tema dejamos grandes expectativas, entonces hay que trabajar mucho en el pr\u00f3ximo tema.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1les son las tres palabras que describen tu m\u00fasica?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00fasica org\u00e1nica, m\u00fasica de coraz\u00f3n y aut\u00e9ntica.<br><br><strong>\u00bfTe gustar\u00eda agregar algo m\u00e1s?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claro, invitarlos a que me sigan en mis redes sociales estoy como <em><strong>@windermx<\/strong><\/em>, siempre estoy al pendiente de las redes, hay un baile en <strong>TikTok<\/strong> de \u201c<strong><em>Vali\u00f3 la pena<\/em><\/strong>\u201d se pueden sumar ah\u00ed y que est\u00e9n al pendiente de mi nuevo disco, vienen muchas sorpresas.<\/p>\n\n\n\n<div style=\"height:10px;\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Recuerda escuchar su nuevo sencillo \u201cVali\u00f3 la pena\u201d, aqu\u00ed te lo compartimos.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"post-video\"><iframe title=\"Vali\u00f3 La Pena - Winder (Video Oficial)\" width=\"1165\" height=\"655\" src=\"https:\/\/www.youtube.com\/embed\/-74D4CgRcro?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n<!--themify_builder_content-->\n<div id=\"themify_builder_content-48353\" data-postid=\"48353\" class=\"themify_builder_content themify_builder_content-48353 themify_builder tf_clear\">\n    <\/div>\n<!--\/themify_builder_content-->\n","protected":false},"excerpt":{"rendered":"<p>Winder es un cantautor e int\u00e9rprete de nacionalidad mexicana que recientemente lanz\u00f3 su nuevo sencillo \u201cVali\u00f3 la pena\u201d, un tema que forma parte de su sexta placa discogr\u00e1fica que saldr\u00e1 en las pr\u00f3ximas semanas. Adem\u00e1s este tema est\u00e1 acompa\u00f1ado de un material visual, que fue grabado en paradis\u00edacas vistas de Quintana Roo, M\u00e9xico. \u00bfQuieres saber [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":48359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"#Entrevista | Winder nos viene a presentar su m\u00e1s reciente sencillo #Vali\u00f3LaPena donde hay toda una historia detr\u00e1s de ella \u00a1Esc\u00fachala ya mismo y disfr\u00fatala como nosotros!","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[117,91],"tags":[1410,1411,358,1412,1413,360,1414,1415],"class_list":["post-48353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento-cine-tv-teatro","category-entrevistas","tag-carlos-vives","tag-jair-alcala","tag-lanzamiento","tag-los-claxons","tag-los-covers-de-winder","tag-sencillo","tag-valio-la-pena","tag-winder","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevista con Winder - Zero Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista con Winder - Zero Magazine\" \/>\n<meta property=\"og:description\" content=\"Winder es un cantautor e int\u00e9rprete de nacionalidad mexicana que recientemente lanz\u00f3 su nuevo sencillo \u201cVali\u00f3 la pena\u201d, un tema que forma parte de su sexta placa discogr\u00e1fica que saldr\u00e1 en las pr\u00f3ximas semanas. Adem\u00e1s este tema est\u00e1 acompa\u00f1ado de un material visual, que fue grabado en paradis\u00edacas vistas de Quintana Roo, M\u00e9xico. \u00bfQuieres saber [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/\" \/>\n<meta property=\"og:site_name\" content=\"Zero Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T17:00:00+00:00\" \/>\n<meta name=\"author\" content=\"zeromagazinemx\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"zeromagazinemx\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/\"},\"author\":{\"name\":\"zeromagazinemx\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#\\\/schema\\\/person\\\/9aed9f33a7c39af3a348b86d723f7773\"},\"headline\":\"Entrevista con Winder\",\"datePublished\":\"2021-06-21T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/\"},\"wordCount\":1237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Carlos Vives\",\"Jair Alcal\u00e1\",\"lanzamiento\",\"los claxons\",\"Los covers de Winder\",\"Sencillo\",\"Vali\u00f3 la pena\",\"Winder\"],\"articleSection\":[\"Entretenimiento\",\"Entrevistas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/\",\"url\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/\",\"name\":\"Entrevista con Winder - Zero Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-06-21T17:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/2021\\\/06\\\/21\\\/entrevista-con-winder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/zeromagazine.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista con Winder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#website\",\"url\":\"https:\\\/\\\/zeromagazine.mx\\\/\",\"name\":\"Zero Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zeromagazine.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#organization\",\"name\":\"Zero Magazine\",\"url\":\"https:\\\/\\\/zeromagazine.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/zeromagazine.mx\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.jpeg?fit=1000%2C1000&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/zeromagazine.mx\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.jpeg?fit=1000%2C1000&ssl=1\",\"width\":1000,\"height\":1000,\"caption\":\"Zero Magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/instagram.com\\\/zeromagazinemx\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/#\\\/schema\\\/person\\\/9aed9f33a7c39af3a348b86d723f7773\",\"name\":\"zeromagazinemx\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/zeromagazine.mx\\\/wp-content\\\/litespeed\\\/avatar\\\/f91dfe5410d5dcb1a576bf8c45983896.jpg?ver=1783619696\",\"url\":\"https:\\\/\\\/zeromagazine.mx\\\/wp-content\\\/litespeed\\\/avatar\\\/f91dfe5410d5dcb1a576bf8c45983896.jpg?ver=1783619696\",\"contentUrl\":\"https:\\\/\\\/zeromagazine.mx\\\/wp-content\\\/litespeed\\\/avatar\\\/f91dfe5410d5dcb1a576bf8c45983896.jpg?ver=1783619696\",\"caption\":\"zeromagazinemx\"},\"url\":\"https:\\\/\\\/zeromagazine.mx\\\/index.php\\\/author\\\/zeromagazinemx\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista con Winder - Zero Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista con Winder - Zero Magazine","og_description":"Winder es un cantautor e int\u00e9rprete de nacionalidad mexicana que recientemente lanz\u00f3 su nuevo sencillo \u201cVali\u00f3 la pena\u201d, un tema que forma parte de su sexta placa discogr\u00e1fica que saldr\u00e1 en las pr\u00f3ximas semanas. Adem\u00e1s este tema est\u00e1 acompa\u00f1ado de un material visual, que fue grabado en paradis\u00edacas vistas de Quintana Roo, M\u00e9xico. \u00bfQuieres saber [&hellip;]","og_url":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/","og_site_name":"Zero Magazine","article_published_time":"2021-06-21T17:00:00+00:00","author":"zeromagazinemx","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"zeromagazinemx","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/#article","isPartOf":{"@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/"},"author":{"name":"zeromagazinemx","@id":"https:\/\/zeromagazine.mx\/#\/schema\/person\/9aed9f33a7c39af3a348b86d723f7773"},"headline":"Entrevista con Winder","datePublished":"2021-06-21T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/"},"wordCount":1237,"commentCount":0,"publisher":{"@id":"https:\/\/zeromagazine.mx\/#organization"},"image":{"@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/#primaryimage"},"thumbnailUrl":"","keywords":["Carlos Vives","Jair Alcal\u00e1","lanzamiento","los claxons","Los covers de Winder","Sencillo","Vali\u00f3 la pena","Winder"],"articleSection":["Entretenimiento","Entrevistas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/","url":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/","name":"Entrevista con Winder - Zero Magazine","isPartOf":{"@id":"https:\/\/zeromagazine.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/#primaryimage"},"image":{"@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-06-21T17:00:00+00:00","breadcrumb":{"@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/21\/entrevista-con-winder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/zeromagazine.mx\/"},{"@type":"ListItem","position":2,"name":"Entrevista con Winder"}]},{"@type":"WebSite","@id":"https:\/\/zeromagazine.mx\/#website","url":"https:\/\/zeromagazine.mx\/","name":"Zero Magazine","description":"","publisher":{"@id":"https:\/\/zeromagazine.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zeromagazine.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/zeromagazine.mx\/#organization","name":"Zero Magazine","url":"https:\/\/zeromagazine.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/zeromagazine.mx\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/zeromagazine.mx\/wp-content\/uploads\/2025\/11\/1.jpeg?fit=1000%2C1000&ssl=1","contentUrl":"https:\/\/i0.wp.com\/zeromagazine.mx\/wp-content\/uploads\/2025\/11\/1.jpeg?fit=1000%2C1000&ssl=1","width":1000,"height":1000,"caption":"Zero Magazine"},"image":{"@id":"https:\/\/zeromagazine.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/instagram.com\/zeromagazinemx"]},{"@type":"Person","@id":"https:\/\/zeromagazine.mx\/#\/schema\/person\/9aed9f33a7c39af3a348b86d723f7773","name":"zeromagazinemx","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/zeromagazine.mx\/wp-content\/litespeed\/avatar\/f91dfe5410d5dcb1a576bf8c45983896.jpg?ver=1783619696","url":"https:\/\/zeromagazine.mx\/wp-content\/litespeed\/avatar\/f91dfe5410d5dcb1a576bf8c45983896.jpg?ver=1783619696","contentUrl":"https:\/\/zeromagazine.mx\/wp-content\/litespeed\/avatar\/f91dfe5410d5dcb1a576bf8c45983896.jpg?ver=1783619696","caption":"zeromagazinemx"},"url":"https:\/\/zeromagazine.mx\/index.php\/author\/zeromagazinemx\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":54270,"url":"https:\/\/zeromagazine.mx\/index.php\/2021\/09\/10\/entrevista-con-alma-paz\/","url_meta":{"origin":48353,"position":0},"title":"Entrevista con Alma Paz\u00a0","author":"zeromagazinemx","date":"10 de septiembre de 2021","format":false,"excerpt":"La cantante de g\u00e9nero urbano Alma Paz, lanz\u00f3 recientemente su \u00faltimo sencillo \u201cI need you\u201d, un tema que busca lograr una conexi\u00f3n con su p\u00fablico a trav\u00e9s de las letras y sonidos. Alma nos cont\u00f3 sobre esta nueva producci\u00f3n y cu\u00e1les son sus planes para los pr\u00f3ximos meses, te invitamos\u2026","rel":"","context":"En \u00abEntretenimiento\u00bb","block_context":{"text":"Entretenimiento","link":"https:\/\/zeromagazine.mx\/index.php\/category\/entretenimiento-cine-tv-teatro\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/iq89DNdEXDw\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":57917,"url":"https:\/\/zeromagazine.mx\/index.php\/2021\/11\/12\/entrevista-a-ven-alva\/","url_meta":{"origin":48353,"position":1},"title":"Entrevista a Ven Alva","author":"zeromagazinemx","date":"12 de noviembre de 2021","format":false,"excerpt":"El cantante y compositor Ven Alva platic\u00f3 con nosotros sobre su sencillo \u201cAntes\u201d, la historia detr\u00e1s y sobre una persona muy especial a la que le dedica este video lleno de detalles. Te invitamos a checar la entrevista completa. Por Mateo Aguilar Plat\u00edcanos un poquito sobre tu m\u00e1s reciente sencillo\u2026","rel":"","context":"En \u00abEntretenimiento\u00bb","block_context":{"text":"Entretenimiento","link":"https:\/\/zeromagazine.mx\/index.php\/category\/entretenimiento-cine-tv-teatro\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/c3fc6-ven-alva.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/c3fc6-ven-alva.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/c3fc6-ven-alva.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/zeromagazinemx.wpcomstaging.com\/wp-content\/uploads\/2022\/02\/c3fc6-ven-alva.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":53746,"url":"https:\/\/zeromagazine.mx\/index.php\/2021\/09\/05\/entrevista-con-japonica\/","url_meta":{"origin":48353,"position":2},"title":"Entrevista con Jap\u00f3nica","author":"zeromagazinemx","date":"5 de septiembre de 2021","format":false,"excerpt":"Jap\u00f3nica la banda de rock pop latino ha lanzado su nuevo sencillo \u201cHaz de luz\u201d, tuvimos la oportunidad de platicar con Erick Morelos sobre esta nueva producci\u00f3n y nos dio algunos adelantos y sorpresas que vendr\u00e1n en pr\u00f3ximos meses. Si quieres saber todos los detalles, te invitamos a checar toda\u2026","rel":"","context":"En \u00abEntretenimiento\u00bb","block_context":{"text":"Entretenimiento","link":"https:\/\/zeromagazine.mx\/index.php\/category\/entretenimiento-cine-tv-teatro\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/hOyIk8lrqQw\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":48179,"url":"https:\/\/zeromagazine.mx\/index.php\/2021\/06\/18\/entrevista-con-asmed\/","url_meta":{"origin":48353,"position":3},"title":"Entrevista con Asmed","author":"zeromagazinemx","date":"18 de junio de 2021","format":false,"excerpt":"El cantante y compositor urbano Asmed, recientemente estren\u00f3 su nuevo sencillo \u201cReh\u00e9n\u201d, un tema que muestra la libertad y sensaciones que nos llevan a situaciones de la vida cotidiana. Este tema habla sobre el encuentro de dos personas que m\u00e1s all\u00e1 de una atracci\u00f3n f\u00edsica y coqueteos, se guardan una\u2026","rel":"","context":"En \u00abEntretenimiento\u00bb","block_context":{"text":"Entretenimiento","link":"https:\/\/zeromagazine.mx\/index.php\/category\/entretenimiento-cine-tv-teatro\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/qvlJDPElPZM\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":52553,"url":"https:\/\/zeromagazine.mx\/index.php\/2021\/08\/20\/entrevista-con-juli-giuliani\/","url_meta":{"origin":48353,"position":4},"title":"Entrevista con Juli Giuliani","author":"zeromagazinemx","date":"20 de agosto de 2021","format":false,"excerpt":"Juli Giuliani llega para conquistarnos con sus mezclas y sonidos al ritmo del beat housero y lo m\u00e1s fresco del hip hop. Recientemente lanz\u00f3 su nuevo sencillo \u201cTrippin\u201d un tema que formar\u00e1 parte de su nuevo \u00e1lbum, un tema fresco y que promete generar una fiesta al instante, tuvimos la\u2026","rel":"","context":"En \u00abEntretenimiento\u00bb","block_context":{"text":"Entretenimiento","link":"https:\/\/zeromagazine.mx\/index.php\/category\/entretenimiento-cine-tv-teatro\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/-3pHCuiOdzs\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":55116,"url":"https:\/\/zeromagazine.mx\/index.php\/2021\/09\/24\/entrevista-con-grand-owel\/","url_meta":{"origin":48353,"position":5},"title":"Entrevista con Grand Owel","author":"zeromagazinemx","date":"24 de septiembre de 2021","format":false,"excerpt":"","rel":"","context":"En \u00abEntretenimiento\u00bb","block_context":{"text":"Entretenimiento","link":"https:\/\/zeromagazine.mx\/index.php\/category\/entretenimiento-cine-tv-teatro\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/_ArlRPcUhg4\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"builder_content":"","_links":{"self":[{"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/posts\/48353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/comments?post=48353"}],"version-history":[{"count":0,"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/posts\/48353\/revisions"}],"wp:attachment":[{"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/media?parent=48353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/categories?post=48353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zeromagazine.mx\/index.php\/wp-json\/wp\/v2\/tags?post=48353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}